{"id":53,"count":5,"description":"","link":"https:\/\/lluistorne.com\/es\/tag\/community-manager-es\/","name":"Community Manager","slug":"community-manager-es","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Archivos de Community Manager - Llu\u00eds Torn\u00e9<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lluistorne.com\/es\/tag\/community-manager-es\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archivos de Community Manager - Llu\u00eds Torn\u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lluistorne.com\/es\/tag\/community-manager-es\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog M\u00e0rqueting Digital Llu\u00eds Torn\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@lluis2014\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/lluistorne.com\/es\/tag\/community-manager-es\/\",\"url\":\"https:\/\/lluistorne.com\/es\/tag\/community-manager-es\/\",\"name\":\"Archivos de Community Manager - Llu\u00eds Torn\u00e9\",\"isPartOf\":{\"@id\":\"https:\/\/lluistorne.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/lluistorne.com\/es\/tag\/community-manager-es\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lluistorne.com\/es\/tag\/community-manager-es\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/lluistorne.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Community Manager\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lluistorne.com\/#website\",\"url\":\"https:\/\/lluistorne.com\/\",\"name\":\"Blog M\u00e0rqueting Digital Llu\u00eds Torn\u00e9\",\"description\":\"Marketing online, social media i anal\u00edtica digital per a projectes digitals, community manager, social media manager\u2026 Blog M\u00e0rqueting Digital Llu\u00eds Torn\u00e9\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lluistorne.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archivos de Community Manager - Llu\u00eds Torn\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lluistorne.com\/es\/tag\/community-manager-es\/","og_locale":"es_ES","og_type":"article","og_title":"Archivos de Community Manager - Llu\u00eds Torn\u00e9","og_url":"https:\/\/lluistorne.com\/es\/tag\/community-manager-es\/","og_site_name":"Blog M\u00e0rqueting Digital Llu\u00eds Torn\u00e9","twitter_card":"summary_large_image","twitter_site":"@lluis2014","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/lluistorne.com\/es\/tag\/community-manager-es\/","url":"https:\/\/lluistorne.com\/es\/tag\/community-manager-es\/","name":"Archivos de Community Manager - Llu\u00eds Torn\u00e9","isPartOf":{"@id":"https:\/\/lluistorne.com\/#website"},"breadcrumb":{"@id":"https:\/\/lluistorne.com\/es\/tag\/community-manager-es\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/lluistorne.com\/es\/tag\/community-manager-es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lluistorne.com\/es\/"},{"@type":"ListItem","position":2,"name":"Community Manager"}]},{"@type":"WebSite","@id":"https:\/\/lluistorne.com\/#website","url":"https:\/\/lluistorne.com\/","name":"Blog M\u00e0rqueting Digital Llu\u00eds Torn\u00e9","description":"Marketing online, social media i anal\u00edtica digital per a projectes digitals, community manager, social media manager\u2026 Blog M\u00e0rqueting Digital Llu\u00eds Torn\u00e9","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lluistorne.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/lluistorne.com\/es\/wp-json\/wp\/v2\/tags\/53"}],"collection":[{"href":"https:\/\/lluistorne.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/lluistorne.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/lluistorne.com\/es\/wp-json\/wp\/v2\/posts?tags=53"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}